{"id":30047,"date":"2020-02-10T10:33:56","date_gmt":"2020-02-10T08:33:56","guid":{"rendered":"https:\/\/clinicaciro.es\/blog\/dras-alonso-casas-simuvad\/"},"modified":"2020-12-10T11:44:07","modified_gmt":"2020-12-10T09:44:07","slug":"dras-alonso-casas-simuvad","status":"publish","type":"post","link":"https:\/\/clinicaciro.es\/en\/blog\/dras-alonso-casas-simuvad\/","title":{"rendered":"La Dra. Sara Alonso y la Dra. Raquel Casas imparten el &#8220;V Curso de simulaci\u00f3n cl\u00ednica en el manejo seguro de la v\u00eda a\u00e9rea&#8221;"},"content":{"rendered":"<p>La <strong>Dra. Sara Alonso<\/strong> y la <strong>Dra. Raquel Casas<\/strong>, anestesistas en Cl\u00ednica CIRO, fueron las encargadas de impartir el &#8220;<strong>V Curso de simulaci\u00f3n cl\u00ednica en el manejo seguro de la v\u00eda a\u00e9rea<\/strong>&#8221; en el Hospital Universitario La Paz.<\/p>\n<p>El curso, <strong>avalado por la SEDAR (Sociedad Espa\u00f1ola de Anestesiolog\u00eda, Reanimaci\u00f3n y Terape\u00fatica del dolor)<\/strong> y multitud de sociedades internacionales, instruy\u00f3 a los asistentes en un manejo adecuado y seguro de la v\u00eda a\u00e9rea, un gran reto al que los anestesi\u00f3logos, intensivistas y m\u00e9dicos de urgencias deben enfrentarse a menudo.<\/p>\n<p>Un aut\u00e9ntico privilegio contar con estas dos grandes profesionales para llevar a cabo las tareas de sedaci\u00f3n y anestesia en Cl\u00ednica CIRO.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Dra. Sara Alonso y la Dra. Raquel Casas, anestesistas en Cl\u00ednica CIRO, fueron las encargadas de impartir el &#8220;V Curso de simulaci\u00f3n cl\u00ednica en el manejo seguro de la v\u00eda a\u00e9rea&#8221; en el Hospital Universitario La Paz. El curso, avalado por la SEDAR (Sociedad Espa\u00f1ola de Anestesiolog\u00eda, Reanimaci\u00f3n y Terape\u00fatica del dolor) y multitud [&hellip;]<\/p>\n","protected":false},"author":10,"featured_media":29645,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1633],"tags":[],"class_list":["post-30047","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad-en"],"_links":{"self":[{"href":"https:\/\/clinicaciro.es\/en\/wp-json\/wp\/v2\/posts\/30047","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/clinicaciro.es\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/clinicaciro.es\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/clinicaciro.es\/en\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/clinicaciro.es\/en\/wp-json\/wp\/v2\/comments?post=30047"}],"version-history":[{"count":0,"href":"https:\/\/clinicaciro.es\/en\/wp-json\/wp\/v2\/posts\/30047\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/clinicaciro.es\/en\/wp-json\/wp\/v2\/media\/29645"}],"wp:attachment":[{"href":"https:\/\/clinicaciro.es\/en\/wp-json\/wp\/v2\/media?parent=30047"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/clinicaciro.es\/en\/wp-json\/wp\/v2\/categories?post=30047"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/clinicaciro.es\/en\/wp-json\/wp\/v2\/tags?post=30047"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}